{"id":20475,"date":"2021-03-09T10:35:07","date_gmt":"2021-03-09T15:35:07","guid":{"rendered":"http:\/\/www.okiok.com\/?p=20475"},"modified":"2021-03-12T11:08:37","modified_gmt":"2021-03-12T16:08:37","slug":"okiok-annonce-la-disponibilite-de-rac-m-identity-3-11-5","status":"publish","type":"post","link":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-11-5\/","title":{"rendered":"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.11.5"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-19669\" src=\"\/wp-content\/uploads\/2020\/08\/racm-identity-medium.png\" alt=\"\" width=\"203\" height=\"81\" \/><br \/>\n<em><a href=\"https:\/\/www.okiok.com\/fr\/produits\/gestion-des-identites-racm-identity\/\">RAC\/M Identity&#x2122;<\/a> est notre solution de gouvernance des identit\u00e9s (GIA) simple et efficace qui permet aux grandes et petites entreprises de comprendre et de g\u00e9rer les relations complexes entre les utilisateurs et leurs acc\u00e8s aux ressources physiques et num\u00e9riques, sur site ou dans l\u2019infonuagique.<\/em><\/p>\n<p><strong>Am\u00e9liorations<\/strong><\/p>\n<ul style=\"margin-left: 40px;\">\n<li>Module: Ajout d&rsquo;un nouveau module permettant de renommer des fichiers en lot (ModuleRenameAndCopyFiles)<\/li>\n<li>Module: Ajout d&rsquo;un nouveau module permettant de transformer le contenu de n&rsquo;importe quel type de fichier en utilisant des expressions r\u00e9guli\u00e8res (ModuleFindAndReplace)<\/li>\n<li>Campagne de r\u00e9vision des acc\u00e8s: Ajout d&rsquo;un nouveau type d&rsquo;approbateur \u00ab\u00a0Certificateur d\u00e9sign\u00e9\u00a0\u00bb permettant d&rsquo;assigner toute les revues \u00e0 un certificateur sp\u00e9cifique<\/li>\n<li>Campagne de r\u00e9vision des acc\u00e8s: Les comptes de service peuvent maintenant \u00eatre inclus dans une campagne de type: \u00ab\u00a0Uniquement les comptes\u00a0\u00bb<\/li>\n<li>Campagne de r\u00e9vision des acc\u00e8s: Il est maintenant possible de choisir \u00ab\u00a0Propri\u00e9taire d&rsquo;actifs\u00a0\u00bb comme type d&rsquo;approbateur dans une campagne de type: \u00ab\u00a0Uniquement les comptes\u00a0\u00bb<\/li>\n<\/ul>\n<p><strong>Correctifs<\/strong><\/p>\n<ul style=\"margin-left: 40px;\">\n<li>Campagne de r\u00e9vision des acc\u00e8s: Plusieurs correctifs dans les campagnes o\u00f9 les certificateurs sont les propri\u00e9taires d&rsquo;actifs<\/li>\n<li>Module: Dans les modules ModuleLocalCopyFiles et ModuleLocalMoveFiles, il est maintenant possible de sp\u00e9cifier un fichier comme source et un r\u00e9pertoire comme destination<\/li>\n<\/ul>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>RAC\/M Identity&#x2122; est notre solution de gouvernance des identit\u00e9s (GIA) simple et efficace qui permet aux grandes et petites entreprises de comprendre et de g\u00e9rer les relations complexes entre les utilisateurs et leurs acc\u00e8s aux ressources physiques et num\u00e9riques, sur site ou dans l\u2019infonuagique. Am\u00e9liorations Module: Ajout d&rsquo;un nouveau module permettant de renommer des fichiers [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174,220,176],"tags":[],"class_list":["post-20475","post","type-post","status-publish","format-standard","hentry","category-nouvelles-fr","category-product-releases-fr","category-racm-identity-fr-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.11.5 - OKIOK - Securit\u00e9 dans un monde en changement<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.11.5 - OKIOK - Securit\u00e9 dans un monde en changement\" \/>\n<meta property=\"og:description\" content=\"RAC\/M Identity&#x2122; est notre solution de gouvernance des identit\u00e9s (GIA) simple et efficace qui permet aux grandes et petites entreprises de comprendre et de g\u00e9rer les relations complexes entre les utilisateurs et leurs acc\u00e8s aux ressources physiques et num\u00e9riques, sur site ou dans l\u2019infonuagique. Am\u00e9liorations Module: Ajout d&rsquo;un nouveau module permettant de renommer des fichiers [&hellip;]\" \/>\n<meta property=\"og:site_name\" content=\"OKIOK - Securit\u00e9 dans un monde en changement\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/okiokdata\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-09T15:35:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-12T16:08:37+00:00\" \/>\n<meta name=\"author\" content=\"Okiok\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OKIOKdata\" \/>\n<meta name=\"twitter:site\" content=\"@OKIOKdata\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Okiok\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.11.5 - OKIOK - Securit\u00e9 dans un monde en changement","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.11.5 - OKIOK - Securit\u00e9 dans un monde en changement","og_description":"RAC\/M Identity&#x2122; est notre solution de gouvernance des identit\u00e9s (GIA) simple et efficace qui permet aux grandes et petites entreprises de comprendre et de g\u00e9rer les relations complexes entre les utilisateurs et leurs acc\u00e8s aux ressources physiques et num\u00e9riques, sur site ou dans l\u2019infonuagique. Am\u00e9liorations Module: Ajout d&rsquo;un nouveau module permettant de renommer des fichiers [&hellip;]","og_site_name":"OKIOK - Securit\u00e9 dans un monde en changement","article_publisher":"https:\/\/www.facebook.com\/okiokdata\/","article_published_time":"2021-03-09T15:35:07+00:00","article_modified_time":"2021-03-12T16:08:37+00:00","author":"Okiok","twitter_card":"summary_large_image","twitter_creator":"@OKIOKdata","twitter_site":"@OKIOKdata","twitter_misc":{"\u00c9crit par":"Okiok","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-11-5\/#article","isPartOf":{"@id":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-11-5\/"},"author":{"name":"Okiok","@id":"https:\/\/www.okiok.com\/fr\/#\/schema\/person\/5d92c7d8760791d758c6a6fe9379a5c5"},"headline":"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.11.5","datePublished":"2021-03-09T15:35:07+00:00","dateModified":"2021-03-12T16:08:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-11-5\/"},"wordCount":226,"commentCount":0,"publisher":{"@id":"https:\/\/www.okiok.com\/fr\/#organization"},"articleSection":["Nouvelles","Product Releases","RAC\/M Identity"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-11-5\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-11-5\/","url":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-11-5\/","name":"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.11.5 - OKIOK - Securit\u00e9 dans un monde en changement","isPartOf":{"@id":"https:\/\/www.okiok.com\/fr\/#website"},"datePublished":"2021-03-09T15:35:07+00:00","dateModified":"2021-03-12T16:08:37+00:00","breadcrumb":{"@id":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-11-5\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-11-5\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-11-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prod.okiok.com\/fr\/"},{"@type":"ListItem","position":2,"name":"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.11.5"}]},{"@type":"WebSite","@id":"https:\/\/www.okiok.com\/fr\/#website","url":"https:\/\/www.okiok.com\/fr\/","name":"OKIOK - Securit\u00e9 dans un monde en changement","description":"","publisher":{"@id":"https:\/\/www.okiok.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.okiok.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.okiok.com\/fr\/#organization","name":"Okiok","url":"https:\/\/www.okiok.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.okiok.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.okiok.com\/wp-content\/uploads\/2017\/06\/logo-okiok-2.png","contentUrl":"https:\/\/www.okiok.com\/wp-content\/uploads\/2017\/06\/logo-okiok-2.png","width":300,"height":369,"caption":"Okiok"},"image":{"@id":"https:\/\/www.okiok.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/okiokdata\/","https:\/\/x.com\/OKIOKdata","https:\/\/www.linkedin.com\/company-beta\/119436\/"]},{"@type":"Person","@id":"https:\/\/www.okiok.com\/fr\/#\/schema\/person\/5d92c7d8760791d758c6a6fe9379a5c5","name":"Okiok","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.okiok.com\/wp-content\/litespeed\/avatar\/ea0c7db598870f60be4ce373e0da470b.jpg?ver=1778613577","url":"https:\/\/www.okiok.com\/wp-content\/litespeed\/avatar\/ea0c7db598870f60be4ce373e0da470b.jpg?ver=1778613577","contentUrl":"https:\/\/www.okiok.com\/wp-content\/litespeed\/avatar\/ea0c7db598870f60be4ce373e0da470b.jpg?ver=1778613577","caption":"Okiok"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/posts\/20475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/comments?post=20475"}],"version-history":[{"count":5,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/posts\/20475\/revisions"}],"predecessor-version":[{"id":20480,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/posts\/20475\/revisions\/20480"}],"wp:attachment":[{"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/media?parent=20475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/categories?post=20475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/tags?post=20475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}