{"id":20620,"date":"2021-08-31T15:13:08","date_gmt":"2021-08-31T20:13:08","guid":{"rendered":"https:\/\/www.okiok.com\/?p=20620"},"modified":"2021-11-05T09:38:03","modified_gmt":"2021-11-05T14:38:03","slug":"utilisation-de-lauthentification-multifacteurs-amf-dans-la-solution-s-filer-portal-v4-15-0","status":"publish","type":"post","link":"https:\/\/www.okiok.com\/fr\/utilisation-de-lauthentification-multifacteurs-amf-dans-la-solution-s-filer-portal-v4-15-0\/","title":{"rendered":"Utilisation de l&rsquo;authentification multifacteurs (AMF) dans la solution S-filer\/Portal v4.15.0"},"content":{"rendered":"<p>Utilisation de l&rsquo;authentification multifacteur (AMF) dans la version 4.15.0 de <a href=\"https:\/\/www.okiok.com\/products\/s-filer-portal\/\">S-Filer\/Portal&#x2122;<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Caract\u00e9ristiques<\/strong><\/p>\n<p>La derni\u00e8re version disponible de la solution <a href=\"https:\/\/www.okiok.com\/products\/s-filer-portal\/\">S-Filer\/Portal&#x2122;<\/a> introduit l&rsquo;authentification multi-facteur (AMF) dans la solution. L&rsquo;introduction de cette nouvelle fonctionnalit\u00e9 n&rsquo;est pas imm\u00e9diatement apparente suite \u00e0 la migration \u00e0 la version 4.15.0. Les utilisateurs pourront continuer d&rsquo;utiliser l&rsquo;application exactement comme ils le faisaient pr\u00e9c\u00e9demment. Le mod\u00e8le d&rsquo;adoption de l&rsquo;AMF dans la solution est individuel et chaque usager doit proc\u00e9der par lui-m\u00eame \u00e0 son adoption. Une fois l&rsquo;AMF adopt\u00e9e par un usager, l&rsquo;impact se r\u00e9percute sur l&rsquo;ensemble des protocoles de communication. Les sections suivantes illustrent ces impacts.<\/p>\n<p>&nbsp;<\/p>\n<p><b>MISE-EN-OEUVRE DE L&rsquo;AMF\u00a0<\/b><\/p>\n<p>La mise-en-oeuvre de l&rsquo;AMF se fait via l&rsquo;interface utilisateur de la solution. Les utilisateurs voulant profiter de cette fonctionnalit\u00e9 peuvent y arriver en activant celle-ci \u00e0 travers leur \u00e9cran de profil. A partir de la version 4.15.0, deux nouveaux sous-menus sont disponibles : Authentification multifacteur (AMF) et jetons d&rsquo;acc\u00e8s. En utilisant l&rsquo;option Authentification multifacteur (AMF), une fen\u00eatre appara\u00eet et permet l&rsquo;activation du TOTP. Vous devez utiliser une application supportant le TOTP comme Microsoft Authenticator ou Google Authenticator pour compl\u00e9ter la mise-en-oeuvre. Une fois le processus d\u00e9marr\u00e9, un Code QR sera affich\u00e9 \u00e0 l&rsquo;\u00e9cran. L&rsquo;application que vous utilisez devrait vous permettre de scanner le Code QR \u00e0 l&rsquo;aide de la cam\u00e9ra de votre appareil mobile. Une fois celui-ci scann\u00e9, un code num\u00e9rique de 6 chiffres va s&rsquo;afficher dans l&rsquo;interface de votre application sur votre appareil mobile. Il est n\u00e9cessaire de proc\u00e9der \u00e0 la confirmation de celui-ci pour compl\u00e9ter l&rsquo;activation de l&rsquo;AMF. Une fois cette op\u00e9ration termin\u00e9e, un code de 6 chiffres sera exig\u00e9 suite \u00e0 une authentification r\u00e9ussie.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-20412\" src=\"\/wp-content\/uploads\/2021\/01\/blog-post-mfa-setup-fr.png\" alt=\"MFA Setup\" width=\"607\" height=\"382\" srcset=\"https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/blog-post-mfa-setup-fr.png 607w, https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/blog-post-mfa-setup-fr-300x189.png 300w\" sizes=\"auto, (max-width: 607px) 100vw, 607px\" \/><\/p>\n<p>Il est aussi possible de g\u00e9n\u00e9rer un jeton d&rsquo;acc\u00e8s \u00e0 travers le second sous-menu nouvellement disponible dans cette version. Un jeton d&rsquo;acc\u00e8s se trouve \u00e0 \u00eatre une alternative \u00e0 un mot de passe r\u00e9gulier. Comme celui-ci est g\u00e9n\u00e9r\u00e9 par la solution et est tr\u00e8s complexe, il est consid\u00e9r\u00e9 comme plus s\u00e9curitaire. Cette fonctionnalit\u00e9 a \u00e9t\u00e9 mise en place pour que les applications devant faire des connexions automatiques (comme les clients Sanctum), qui ne peuvent demander un second facteur d&rsquo;authentification, continuent de fonctionner m\u00eame si le compte de l&rsquo;utilisateur est configur\u00e9 pour demander l&rsquo;AMF. Ainsi l&rsquo;utilisateur peut configurer l&rsquo;AMF sur son compte et l&rsquo;utiliser lorsqu&rsquo;il s&rsquo;authentifie directement, mais configurer ses applications pour utiliser des jetons d&rsquo;authentification et ainsi faire des authentifications sans AMF. Plusieurs jetons d&rsquo;acc\u00e8s peuvent \u00eatre ajout\u00e9s \u00e0 un m\u00eame compte pour permettre \u00e0 chaque application d&rsquo;utiliser un jeton diff\u00e9rent. Si un jeton est compromis, il peut rapidement \u00eatre r\u00e9pudi\u00e9 par un utilisateur ou un administrateur syst\u00e8me.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-20415\" src=\"\/wp-content\/uploads\/2021\/01\/blog-post-mfa-setup-access-token-fr.png\" alt=\"MFA Setup Access Token\" width=\"600\" height=\"421\" srcset=\"https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/blog-post-mfa-setup-access-token-fr.png 600w, https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/blog-post-mfa-setup-access-token-fr-300x211.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><b>UTILISATION DE L&rsquo;AMF DANS L&rsquo;INTERFACE WEB<\/b><\/p>\n<p>L&rsquo;utilisation de l&rsquo;AMF \u00e0 travers l&rsquo;interface utilisateur n&rsquo;est pr\u00e9sente que lorsque le bon mot de passe a \u00e9t\u00e9 entr\u00e9. Dans ce cas, un panneau interm\u00e9diaire est pr\u00e9sent\u00e9 et exige \u00e0 l&rsquo;utilisateur de fournir un code de 6 chiffres. L&rsquo;utilisateur doit ouvrir son application mobile \u00ab\u00a0authenticator\u00a0\u00bb, s\u00e9lectionner le compte correspondant \u00e0 son compte S-Filer et entrer le code. Si le code fourni correspond, l&rsquo;utilisateur sera redirig\u00e9 vers les pages de l&rsquo;application. Il faut noter que la saisie successive de mauvais codes MFA(TOTP) pourrait verrouiller le compte de l&rsquo;utilisateur.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-20418\" src=\"\/wp-content\/uploads\/2021\/01\/blog-post-mfa-login-fr.png\" alt=\"MFA Login\" width=\"557\" height=\"346\" srcset=\"https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/blog-post-mfa-login-fr.png 557w, https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/blog-post-mfa-login-fr-300x186.png 300w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><b>UTILISATION DE l&rsquo;AMF AVEC LE PROTOCOLE SFTP<\/b><\/p>\n<p>L&rsquo;introduction de l&rsquo;AMF dans la solution ne se limite pas \u00e0 l&rsquo;interface graphique. Si un profil utilisateur est configur\u00e9 pour utiliser l&rsquo;AMF avec TOTP, alors le code de 6 chiffres sera exig\u00e9 lors de transferts de fichiers aussi (\u00e0 la condition bien s\u00fbr d&rsquo;utiliser un mot de passe, car l&rsquo;utilisation d&rsquo;un jeton d&rsquo;acc\u00e8s outrepasse la n\u00e9cessit\u00e9 de fournir un second facteur d&rsquo;authentification). L&rsquo;exp\u00e9rience utilisateur pourra par contre varier en fonction du client utilis\u00e9. La fonctionnalit\u00e9 est disponible autant via les clients utilisant une interface graphique que pour les clients fonctionnant en mode ligne de commande. Il peut \u00eatre n\u00e9cessaire d&rsquo;activer le mode interactif de votre client graphique pour que la saisie du TOTP puisse \u00eatre possible.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-20422\" src=\"\/wp-content\/uploads\/2021\/01\/blog-post-mfa-login-ssh-fr.png\" alt=\"SFTP MFA\" width=\"314\" height=\"331\" srcset=\"https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/blog-post-mfa-login-ssh-fr.png 314w, https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/blog-post-mfa-login-ssh-fr-285x300.png 285w\" sizes=\"auto, (max-width: 314px) 100vw, 314px\" \/><\/p>\n<p>L&rsquo;exp\u00e9rience utilisateur en mode ligne de commande sera similaire. Le mot de passe de l&rsquo;usager sera exig\u00e9 une premi\u00e8re fois, viendra ensuite une seconde question pour laquelle l&rsquo;utilisateur devra fournir les 6 chiffres de son code TOTP.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-20425\" src=\"\/wp-content\/uploads\/2021\/01\/image_2021-02-24_163151.png\" alt=\"MFA SCP\" width=\"658\" height=\"282\" srcset=\"https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/image_2021-02-24_163151.png 658w, https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/image_2021-02-24_163151-300x129.png 300w\" sizes=\"auto, (max-width: 658px) 100vw, 658px\" \/><\/p>\n<p><b>UTILISATION DE L&rsquo;AMF AVEC LES OUTILS LIGNES DE COMMANDES S-FILER<\/b><\/p>\n<p>Les outils pour ligne de commande <em>sfiler-cli<\/em> et <em>sfiler-admin-cli<\/em> ont aussi \u00e9t\u00e9 modifi\u00e9s pour supporter l&rsquo;AMF. Dans le cas du <em>sfiler-cli<\/em> (outil utilis\u00e9 pour effectuer des transferts de fichiers), si l&rsquo;utilisateur a activ\u00e9 l&rsquo;AMF, il sera n\u00e9cessaire de fournir le code de 6 chiffres avant le d\u00e9marrage du transfert. Comme pour les autres clients et protocoles de la solution, il est aussi possible d&rsquo;utiliser des jetons d&rsquo;acc\u00e8s comme mot de passe avec les CLIs. Lorsqu&rsquo;un jeton d&rsquo;acc\u00e8s est utilis\u00e9, il n&rsquo;est pas n\u00e9cessaire de fournir le code TOTP m\u00eame si le profil utilisateur est configur\u00e9 pour l&rsquo;utiliser.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-20428\" src=\"\/wp-content\/uploads\/2021\/01\/blog-post-mfa-sfiler-cli-fr.png\" alt=\"MFA SFILER-CLI\" width=\"997\" height=\"367\" srcset=\"https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/blog-post-mfa-sfiler-cli-fr.png 997w, https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/blog-post-mfa-sfiler-cli-fr-300x110.png 300w, https:\/\/www.okiok.com\/wp-content\/uploads\/2021\/01\/blog-post-mfa-sfiler-cli-fr-768x283.png 768w\" sizes=\"auto, (max-width: 997px) 100vw, 997px\" \/><\/p>\n<p>Le <em>sfiler-admin-cli<\/em> exigera aussi un code de 6 chiffres si l&rsquo;utilisateur a activ\u00e9 la fonctionnalit\u00e9 dans son profil utilisateur. De nouvelles fonctions de gestion de l&rsquo;AMF sont aussi disponibles avec cette nouvelle version qui permettent la gestion du MFA :<\/p>\n<ul>\n<li>add-auth-factor-access-token, qui permet la cr\u00e9ation d&rsquo;un jeton d&rsquo;acc\u00e8s pour un utilisateur.<\/li>\n<li>delete-auth-factor-access-token, qui permet la suppression de jetons d&rsquo;acc\u00e8s pour un utilisateur.<\/li>\n<li>delete-auth-factor-totp, qui permet de faire la suppression de la configuration TOTP d&rsquo;un utilisateur.<\/li>\n<li>list-auth-factor-access-token, qui permet d&rsquo;obtenir la liste des jetons d&rsquo;acc\u00e8s pour un utilisateur.<\/li>\n<\/ul>\n<p>Utiliser le param\u00e8tre &#8211;help (-h) pour obtenir le d\u00e9tail de tous les param\u00e8tres et options possibles pour chacune des commandes offertes par les CLIs de la solution.<\/p>\n<p>&nbsp;<\/p>\n<p><b>UTILISATION DE L&rsquo;AMF AVEC L&rsquo;API REST<\/b><\/p>\n<p>L&rsquo;API REST a \u00e9t\u00e9 bonifi\u00e9 de fa\u00e7on \u00e0 offrir les m\u00eames fonctionnalit\u00e9s que l&rsquo;interface utilisateur. Une s\u00e9rie de nouveaux services sont offerts pour g\u00e9rer les TOTP et les jetons d&rsquo;acc\u00e8s des utilisateurs. Il est donc possible d&rsquo;automatiser la configuration des utilisateurs en utilisant l&rsquo;API REST. Comme pour l&rsquo;ensemble de l&rsquo;API REST, vous \u00eates invit\u00e9 \u00e0 consulter la documentation disponible directement \u00e0 partir de l&rsquo;url du serveur:<br \/>\n<code>https:\/\/[server_url]\/sfiler\/server\/api\/docs\/<\/code><\/p>\n<p>Les nouveaux services sont disponibles \u00e0 travers deux niveaux : <em>auth<\/em> et <em>users<\/em>.<\/p>\n<p>Les services <em>auth<\/em> ont pour objectif de proc\u00e9der aux appels reli\u00e9s \u00e0 l&rsquo;authentification:<\/p>\n<ul>\n<li>POST : \/auth\/change-password<\/li>\n<li>POST: \/auth\/mfa\/totp\/validate-code<\/li>\n<\/ul>\n<p>Les services <em>users<\/em> ont pour objectif de permettre la gestion des facteurs d&rsquo;authentification pour les usagers :<\/p>\n<ul>\n<li>POST : \/users\/{id}\/auth-factors\/access-tokens<\/li>\n<li>GET : \/users\/{id}\/auth-factors\/access-tokens<\/li>\n<li>DELETE: \/users\/{id}\/auth-factors\/access-tokens<\/li>\n<li>GET: \/users\/{id}\/auth-factors\/access-tokens\/{accessTokenId}<\/li>\n<li>DELETE: \/users\/{id}\/auth-factors\/access-tokens\/{accessTokenId}<\/li>\n<li>POST: \/users\/{id}\/auth-factors\/totp<\/li>\n<li>GET: \/users\/{id}\/auth-factors\/totp<\/li>\n<li>DELETE: \/users\/{id}\/auth-factors\/totp<\/li>\n<li>GET: \/users\/{id}\/auth-factors\/totp\/{totpId}<\/li>\n<li>DELETE: \/users\/{id}\/auth-factors\/totp\/{totpId}<\/li>\n<li>POST: \/users\/{id}\/auth-factors\/totp\/{totpId}\/complete<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Utilisation de l&rsquo;authentification multifacteur (AMF) dans la version 4.15.0 de S-Filer\/Portal&#x2122;. &nbsp; Caract\u00e9ristiques La derni\u00e8re version disponible de la solution S-Filer\/Portal&#x2122; introduit l&rsquo;authentification multi-facteur (AMF) dans la solution. L&rsquo;introduction de cette nouvelle fonctionnalit\u00e9 n&rsquo;est pas imm\u00e9diatement apparente suite \u00e0 la migration \u00e0 la version 4.15.0. Les utilisateurs pourront continuer d&rsquo;utiliser l&rsquo;application exactement comme ils le [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174,220,177],"tags":[],"class_list":["post-20620","post","type-post","status-publish","format-standard","hentry","category-nouvelles-fr","category-product-releases-fr","category-s-filerportal-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Utilisation de l&#039;authentification multifacteurs (AMF) dans la solution S-filer\/Portal v4.15.0 - OKIOK - Securit\u00e9 dans un monde en changement<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Utilisation de l&#039;authentification multifacteurs (AMF) dans la solution S-filer\/Portal v4.15.0 - OKIOK - Securit\u00e9 dans un monde en changement\" \/>\n<meta property=\"og:description\" content=\"Utilisation de l&rsquo;authentification multifacteur (AMF) dans la version 4.15.0 de S-Filer\/Portal&#x2122;. &nbsp; Caract\u00e9ristiques La derni\u00e8re version disponible de la solution S-Filer\/Portal&#x2122; introduit l&rsquo;authentification multi-facteur (AMF) dans la solution. L&rsquo;introduction de cette nouvelle fonctionnalit\u00e9 n&rsquo;est pas imm\u00e9diatement apparente suite \u00e0 la migration \u00e0 la version 4.15.0. Les utilisateurs pourront continuer d&rsquo;utiliser l&rsquo;application exactement comme ils le [&hellip;]\" \/>\n<meta property=\"og:site_name\" content=\"OKIOK - Securit\u00e9 dans un monde en changement\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/okiokdata\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-31T20:13:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-05T14:38:03+00:00\" \/>\n<meta name=\"author\" content=\"Okiok\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OKIOKdata\" \/>\n<meta name=\"twitter:site\" content=\"@OKIOKdata\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Okiok\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Utilisation de l'authentification multifacteurs (AMF) dans la solution S-filer\/Portal v4.15.0 - OKIOK - Securit\u00e9 dans un monde en changement","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Utilisation de l'authentification multifacteurs (AMF) dans la solution S-filer\/Portal v4.15.0 - OKIOK - Securit\u00e9 dans un monde en changement","og_description":"Utilisation de l&rsquo;authentification multifacteur (AMF) dans la version 4.15.0 de S-Filer\/Portal&#x2122;. &nbsp; Caract\u00e9ristiques La derni\u00e8re version disponible de la solution S-Filer\/Portal&#x2122; introduit l&rsquo;authentification multi-facteur (AMF) dans la solution. L&rsquo;introduction de cette nouvelle fonctionnalit\u00e9 n&rsquo;est pas imm\u00e9diatement apparente suite \u00e0 la migration \u00e0 la version 4.15.0. Les utilisateurs pourront continuer d&rsquo;utiliser l&rsquo;application exactement comme ils le [&hellip;]","og_site_name":"OKIOK - Securit\u00e9 dans un monde en changement","article_publisher":"https:\/\/www.facebook.com\/okiokdata\/","article_published_time":"2021-08-31T20:13:08+00:00","article_modified_time":"2021-11-05T14:38:03+00:00","author":"Okiok","twitter_card":"summary_large_image","twitter_creator":"@OKIOKdata","twitter_site":"@OKIOKdata","twitter_misc":{"\u00c9crit par":"Okiok","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.okiok.com\/fr\/utilisation-de-lauthentification-multifacteurs-amf-dans-la-solution-s-filer-portal-v4-15-0\/#article","isPartOf":{"@id":"https:\/\/www.okiok.com\/fr\/utilisation-de-lauthentification-multifacteurs-amf-dans-la-solution-s-filer-portal-v4-15-0\/"},"author":{"name":"Okiok","@id":"https:\/\/www.okiok.com\/fr\/#\/schema\/person\/5d92c7d8760791d758c6a6fe9379a5c5"},"headline":"Utilisation de l&rsquo;authentification multifacteurs (AMF) dans la solution S-filer\/Portal v4.15.0","datePublished":"2021-08-31T20:13:08+00:00","dateModified":"2021-11-05T14:38:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.okiok.com\/fr\/utilisation-de-lauthentification-multifacteurs-amf-dans-la-solution-s-filer-portal-v4-15-0\/"},"wordCount":1234,"commentCount":0,"publisher":{"@id":"https:\/\/www.okiok.com\/fr\/#organization"},"articleSection":["Nouvelles","Product Releases","S-Filer\/Portal"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.okiok.com\/fr\/utilisation-de-lauthentification-multifacteurs-amf-dans-la-solution-s-filer-portal-v4-15-0\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.okiok.com\/fr\/utilisation-de-lauthentification-multifacteurs-amf-dans-la-solution-s-filer-portal-v4-15-0\/","url":"https:\/\/www.okiok.com\/fr\/utilisation-de-lauthentification-multifacteurs-amf-dans-la-solution-s-filer-portal-v4-15-0\/","name":"Utilisation de l'authentification multifacteurs (AMF) dans la solution S-filer\/Portal v4.15.0 - OKIOK - Securit\u00e9 dans un monde en changement","isPartOf":{"@id":"https:\/\/www.okiok.com\/fr\/#website"},"datePublished":"2021-08-31T20:13:08+00:00","dateModified":"2021-11-05T14:38:03+00:00","breadcrumb":{"@id":"https:\/\/www.okiok.com\/fr\/utilisation-de-lauthentification-multifacteurs-amf-dans-la-solution-s-filer-portal-v4-15-0\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.okiok.com\/fr\/utilisation-de-lauthentification-multifacteurs-amf-dans-la-solution-s-filer-portal-v4-15-0\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.okiok.com\/fr\/utilisation-de-lauthentification-multifacteurs-amf-dans-la-solution-s-filer-portal-v4-15-0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prod.okiok.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Utilisation de l&rsquo;authentification multifacteurs (AMF) dans la solution S-filer\/Portal v4.15.0"}]},{"@type":"WebSite","@id":"https:\/\/www.okiok.com\/fr\/#website","url":"https:\/\/www.okiok.com\/fr\/","name":"OKIOK - Securit\u00e9 dans un monde en changement","description":"","publisher":{"@id":"https:\/\/www.okiok.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.okiok.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.okiok.com\/fr\/#organization","name":"Okiok","url":"https:\/\/www.okiok.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.okiok.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.okiok.com\/wp-content\/uploads\/2017\/06\/logo-okiok-2.png","contentUrl":"https:\/\/www.okiok.com\/wp-content\/uploads\/2017\/06\/logo-okiok-2.png","width":300,"height":369,"caption":"Okiok"},"image":{"@id":"https:\/\/www.okiok.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/okiokdata\/","https:\/\/x.com\/OKIOKdata","https:\/\/www.linkedin.com\/company-beta\/119436\/"]},{"@type":"Person","@id":"https:\/\/www.okiok.com\/fr\/#\/schema\/person\/5d92c7d8760791d758c6a6fe9379a5c5","name":"Okiok","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.okiok.com\/wp-content\/litespeed\/avatar\/ea0c7db598870f60be4ce373e0da470b.jpg?ver=1784059908","url":"https:\/\/www.okiok.com\/wp-content\/litespeed\/avatar\/ea0c7db598870f60be4ce373e0da470b.jpg?ver=1784059908","contentUrl":"https:\/\/www.okiok.com\/wp-content\/litespeed\/avatar\/ea0c7db598870f60be4ce373e0da470b.jpg?ver=1784059908","caption":"Okiok"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/posts\/20620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/comments?post=20620"}],"version-history":[{"count":14,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/posts\/20620\/revisions"}],"predecessor-version":[{"id":21285,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/posts\/20620\/revisions\/21285"}],"wp:attachment":[{"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/media?parent=20620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/categories?post=20620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/tags?post=20620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}