{"id":21326,"date":"2021-10-04T10:28:53","date_gmt":"2021-10-04T15:28:53","guid":{"rendered":"https:\/\/www.okiok.com\/?p=21326"},"modified":"2021-10-04T12:42:53","modified_gmt":"2021-10-04T17:42:53","slug":"okiok-annonce-la-disponibilite-de-rac-m-identity-3-13-3","status":"publish","type":"post","link":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-13-3\/","title":{"rendered":"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.13.3"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-19669\" src=\"\/wp-content\/uploads\/2020\/08\/racm-identity-medium.png\" alt=\"\" width=\"203\" height=\"81\" \/><br \/>\n<em><a href=\"https:\/\/www.okiok.com\/fr\/produits\/gestion-des-identites-racm-identity\/\">RAC\/M Identity&#x2122;<\/a> est notre solution de gouvernance des identit\u00e9s (GIA) simple et efficace qui permet aux grandes et petites entreprises de comprendre et de g\u00e9rer les relations complexes entre les utilisateurs et leurs acc\u00e8s aux ressources physiques et num\u00e9riques, sur site ou dans l\u2019infonuagique.<\/em><\/p>\n<p><strong>AM\u00c9LIORATIONS<\/strong><\/p>\n<ul style=\"margin-left: 40px;\">\n<li>Le module ModuleLocalDeleteFiles supporte maintenant le caract\u00e8re de remplacement &lsquo;*&rsquo; pour la suppression de fichiers en lot. Par exemple, conf\/csv\/*.csv supprimera tous les fichiers avec l&rsquo;extension .csv du r\u00e9pertoire csv #2722<\/li>\n<li>Ajout d&rsquo;un param\u00e8tre dans le module ModuleDeleteNonUpdatedSinceDate permettant de dissocier les appariements lorsque ex\u00e9cut\u00e9 en mode Terminaison de compte #2527<\/li>\n<li>Dans la page de d\u00e9tails de campagne, la liste des certificateurs a maintenant de la pagination et des options de filtres #2719<\/li>\n<li>Dans la modale de d\u00e9tails d&rsquo;un groupe dans une campagne de revue des r\u00f4les, on affiche maintenant la date d&rsquo;assignation du r\u00f4le dans la matrice des membres #2711<\/li>\n<li>Ajout de plusieurs index \u00e0 la base de donn\u00e9es afin d&rsquo;am\u00e9liorer la performance de certaines requ\u00eates #2720<\/li>\n<\/ul>\n<p><strong>CORRECTIFS<\/strong><\/p>\n<ul style=\"margin-left: 40px;\">\n<li>Le module ModuleCorrelationByDomainAccountName fonctionne maintenant correctement avec le caract\u00e8re de remplacement &lsquo;%&rsquo; #1825<\/li>\n<li>Lors d&rsquo;une terminaison et d&rsquo;une extension de campagne, les courriels de notifications sont maintenant envoy\u00e9s aux bonnes personnes #2716<\/li>\n<li>La suppression d&rsquo;une campagne de r\u00e9vision des r\u00f4les ne retourne plus d&rsquo;erreur #2721<\/li>\n<li>Lors de l&rsquo;importation via un connecteur ICF, l&rsquo;importation ne s&rsquo;arr\u00eate plus de mani\u00e8re silencieuse si une des cl\u00e9s sp\u00e9cifi\u00e9es dans le module est &lsquo;null&rsquo; #2708<\/li>\n<li>Le module ModuleDeleteNonUpdatedSinceDate ex\u00e9cut\u00e9 en mode Terminaison de compte r\u00e9initialise maintenant le statut de corr\u00e9lation #2527<\/li>\n<li>L&rsquo;envoi manuel de rappel de campagne est maintenant fonctionnel pour une campagne de r\u00e9vision des r\u00f4les #2710<\/li>\n<li>La certification d&rsquo;un groupe supprim\u00e9 dans une campagne de r\u00e9vision des r\u00f4les est maintenant fonctionnelle #2718<\/li>\n<li>Dans la liste des t\u00e2ches en mode administrateur, le filtre \u00c9tat est maintenant au dessus de la bonne colonne #2727<\/li>\n<li>Correction de la mauvaise redirection faite apr\u00e8s une authentification de type SSO<\/li>\n<li>Correction d&rsquo;une erreur intermittente survenant lorsqu&rsquo;un usager tente d&rsquo;acc\u00e9der \u00e0 RACM depuis un courriel<\/li>\n<\/ul>\n<ul style=\"margin-left: 40px;\">\n<li style=\"list-style-type: none;\"><\/li>\n<\/ul>\n<ul style=\"margin-left: 40px;\">\n<li style=\"list-style-type: none;\"><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>RAC\/M Identity&#x2122; est notre solution de gouvernance des identit\u00e9s (GIA) simple et efficace qui permet aux grandes et petites entreprises de comprendre et de g\u00e9rer les relations complexes entre les utilisateurs et leurs acc\u00e8s aux ressources physiques et num\u00e9riques, sur site ou dans l\u2019infonuagique. AM\u00c9LIORATIONS Le module ModuleLocalDeleteFiles supporte maintenant le caract\u00e8re de remplacement &lsquo;*&rsquo; [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174,220,176],"tags":[],"class_list":["post-21326","post","type-post","status-publish","format-standard","hentry","category-nouvelles-fr","category-product-releases-fr","category-racm-identity-fr-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.13.3 - OKIOK - Securit\u00e9 dans un monde en changement<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.13.3 - OKIOK - Securit\u00e9 dans un monde en changement\" \/>\n<meta property=\"og:description\" content=\"RAC\/M Identity&#x2122; est notre solution de gouvernance des identit\u00e9s (GIA) simple et efficace qui permet aux grandes et petites entreprises de comprendre et de g\u00e9rer les relations complexes entre les utilisateurs et leurs acc\u00e8s aux ressources physiques et num\u00e9riques, sur site ou dans l\u2019infonuagique. AM\u00c9LIORATIONS Le module ModuleLocalDeleteFiles supporte maintenant le caract\u00e8re de remplacement &lsquo;*&rsquo; [&hellip;]\" \/>\n<meta property=\"og:site_name\" content=\"OKIOK - Securit\u00e9 dans un monde en changement\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/okiokdata\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-04T15:28:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-04T17:42:53+00:00\" \/>\n<meta name=\"author\" content=\"Okiok\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OKIOKdata\" \/>\n<meta name=\"twitter:site\" content=\"@OKIOKdata\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Okiok\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.13.3 - OKIOK - Securit\u00e9 dans un monde en changement","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.13.3 - OKIOK - Securit\u00e9 dans un monde en changement","og_description":"RAC\/M Identity&#x2122; est notre solution de gouvernance des identit\u00e9s (GIA) simple et efficace qui permet aux grandes et petites entreprises de comprendre et de g\u00e9rer les relations complexes entre les utilisateurs et leurs acc\u00e8s aux ressources physiques et num\u00e9riques, sur site ou dans l\u2019infonuagique. AM\u00c9LIORATIONS Le module ModuleLocalDeleteFiles supporte maintenant le caract\u00e8re de remplacement &lsquo;*&rsquo; [&hellip;]","og_site_name":"OKIOK - Securit\u00e9 dans un monde en changement","article_publisher":"https:\/\/www.facebook.com\/okiokdata\/","article_published_time":"2021-10-04T15:28:53+00:00","article_modified_time":"2021-10-04T17:42:53+00:00","author":"Okiok","twitter_card":"summary_large_image","twitter_creator":"@OKIOKdata","twitter_site":"@OKIOKdata","twitter_misc":{"\u00c9crit par":"Okiok","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-13-3\/#article","isPartOf":{"@id":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-13-3\/"},"author":{"name":"Okiok","@id":"https:\/\/www.okiok.com\/fr\/#\/schema\/person\/5d92c7d8760791d758c6a6fe9379a5c5"},"headline":"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.13.3","datePublished":"2021-10-04T15:28:53+00:00","dateModified":"2021-10-04T17:42:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-13-3\/"},"wordCount":377,"commentCount":0,"publisher":{"@id":"https:\/\/www.okiok.com\/fr\/#organization"},"articleSection":["Nouvelles","Product Releases","RAC\/M Identity"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-13-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-13-3\/","url":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-13-3\/","name":"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.13.3 - OKIOK - Securit\u00e9 dans un monde en changement","isPartOf":{"@id":"https:\/\/www.okiok.com\/fr\/#website"},"datePublished":"2021-10-04T15:28:53+00:00","dateModified":"2021-10-04T17:42:53+00:00","breadcrumb":{"@id":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-13-3\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-13-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.okiok.com\/fr\/okiok-annonce-la-disponibilite-de-rac-m-identity-3-13-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prod.okiok.com\/fr\/"},{"@type":"ListItem","position":2,"name":"OKIOK annonce la disponibilit\u00e9 de RAC\/M Identity 3.13.3"}]},{"@type":"WebSite","@id":"https:\/\/www.okiok.com\/fr\/#website","url":"https:\/\/www.okiok.com\/fr\/","name":"OKIOK - Securit\u00e9 dans un monde en changement","description":"","publisher":{"@id":"https:\/\/www.okiok.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.okiok.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.okiok.com\/fr\/#organization","name":"Okiok","url":"https:\/\/www.okiok.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.okiok.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.okiok.com\/wp-content\/uploads\/2017\/06\/logo-okiok-2.png","contentUrl":"https:\/\/www.okiok.com\/wp-content\/uploads\/2017\/06\/logo-okiok-2.png","width":300,"height":369,"caption":"Okiok"},"image":{"@id":"https:\/\/www.okiok.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/okiokdata\/","https:\/\/x.com\/OKIOKdata","https:\/\/www.linkedin.com\/company-beta\/119436\/"]},{"@type":"Person","@id":"https:\/\/www.okiok.com\/fr\/#\/schema\/person\/5d92c7d8760791d758c6a6fe9379a5c5","name":"Okiok","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.okiok.com\/wp-content\/litespeed\/avatar\/ea0c7db598870f60be4ce373e0da470b.jpg?ver=1784059908","url":"https:\/\/www.okiok.com\/wp-content\/litespeed\/avatar\/ea0c7db598870f60be4ce373e0da470b.jpg?ver=1784059908","contentUrl":"https:\/\/www.okiok.com\/wp-content\/litespeed\/avatar\/ea0c7db598870f60be4ce373e0da470b.jpg?ver=1784059908","caption":"Okiok"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/posts\/21326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/comments?post=21326"}],"version-history":[{"count":2,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/posts\/21326\/revisions"}],"predecessor-version":[{"id":21328,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/posts\/21326\/revisions\/21328"}],"wp:attachment":[{"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/media?parent=21326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/categories?post=21326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.okiok.com\/fr\/wp-json\/wp\/v2\/tags?post=21326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}